{"id":90303,"date":"2025-04-04T14:39:04","date_gmt":"2025-04-04T20:39:04","guid":{"rendered":"https:\/\/inmoment.com\/lp\/conversational-intelligence-trends-report\/"},"modified":"2025-04-08T21:20:44","modified_gmt":"2025-04-09T03:20:44","slug":"conversational-intelligence-trends-report","status":"publish","type":"lp","link":"https:\/\/inmoment.com\/en-au\/lp\/conversational-intelligence-trends-report\/","title":{"rendered":"Conversational Intelligence Trends Report"},"content":{"rendered":"<section id=\"block-e58c5213b71869130422613cf26b8587\" class=\"content-block gated-featured-asset-block gated-feature-asset-block-right alignfull has-background color-as-background background-albatross\" style=\"\">\n\t\t<div class=\"gated-featured-asset-block-inner\">\n\t\t\t\n\t\t\t\t\t\t\t\n\n\n\t<span class=\"hs-gated-content-reveal-overlay  \"><\/span>\n\t<div class=\"hs-form-sticky-wrap   \">\n\t\t\n\n\t\t<div id=\"hubspot-form-6a57456405f34\" class=\"block-hubspot-form hs-form-outer  \" data-chili=\"\" data-form-id=\"32e872b5-396b-4da6-905d-57c7e16b5b15\" >\n\t\t\t\t\t\t\t\t\t<!-- <span class=\"hs-gated-content-reveal-overlay\"><\/span> -->\n\t\t\t\t\t\t\n\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<h3 class=\"hs-form-title   \">Get the Report<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"skeleton-loader\" id=\"loading-indicator-hubspot-form-6a57456405f34\">\n\t\t\t\t\t<div class=\"skeleton-field formpulse delay-1\">\n\t\t\t\t\t\t<div class=\"skeleton-label\"><\/div>\n\t\t\t\t\t\t<div class=\"skeleton-input\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"skeleton-field formpulse delay-2\">\n\t\t\t\t\t\t<div class=\"skeleton-label\"><\/div>\n\t\t\t\t\t\t<div class=\"skeleton-input\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"skeleton-field formpulse delay-3\">\n\t\t\t\t\t\t<div class=\"skeleton-label\"><\/div>\n\t\t\t\t\t\t<div class=\"skeleton-input\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<script>\n\t\t\t\t\t\n\n\t\t\t\t\thsformEmbedJs.addEventListener('load', function(event_6a57456405f34) {\n\n\t\t\t\t\tvar gatedContentType = 'pdf';\n\t\t\t\t\tvar timeoutTime = 0;\n\n\t\t\t\t\t\t\/\/ Set up functions\n\t\t\t\t\t\tfunction onFormReadyFunction($form) {\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/\/ Hide the loading indicator here if ZIFC not enabled\n\t\t\t\t\t\t\t\tif (document.getElementById('loading-indicator-hubspot-form-6a57456405f34'))\n\t\t\t\t\t\t\t\t\tdocument.getElementById('loading-indicator-hubspot-form-6a57456405f34').style.display = 'none';\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/\/ Gated content known user check\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/*\n\t\t\t\t\t\t\tif(( localStorage.getItem('hasSubmittedForm') === 'true' && document.cookie.toLowerCase().indexOf('hubspotutk') > -1 ) && (gatedContentType === 'pdf' || gatedContentType === 'popupPdf')) {\n\t\t\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.skeleton-loader').style.display = 'none';\n\t\t\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.form_target').style.display = 'none';\n\t\t\t\t\t\t\t\tlet submittedMessageCustom = $form[0].closest('.block-hubspot-form').appendChild(document.createElement('div'));\n\t\t\t\t\t\t\t\tsubmittedMessageCustom.classList.add('submitted-message-custom');\n\n\t\t\t\t\t\t\t\tif (gatedContentType === 'popupPdf') submittedMessageCustom.classList.add('text-center');\n\n\t\t\t\t\t\t\t\tsubmittedMessageCustom.innerHTML = '<a href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/04\/2025-Contact-Centre-Trends-in-APAC.pdf\" class=\"known-user-download header-cta-button button background-tsunami inline-block px-8 py-4 mb-4\" target=\"_blank\" data-last-asset=\"2025 Contact Centre Trends in APAC (Report)\"><span>Download Now<\/span><span class=\"item-icon order-3 right-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Pro 6.5.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2024 Fonticons, Inc. --><path d=\"M288 32c0-17.7-14.3-32-32-32s-32 14.3-32 32V274.7l-73.4-73.4c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3l128 128c12.5 12.5 32.8 12.5 45.3 0l128-128c12.5-12.5 12.5-32.8 0-45.3s-32.8-12.5-45.3 0L288 274.7V32zM64 352c-35.3 0-64 28.7-64 64v32c0 35.3 28.7 64 64 64H448c35.3 0 64-28.7 64-64V416c0-35.3-28.7-64-64-64H346.5l-45.3 45.3c-25 25-65.5 25-90.5 0L165.5 352H64zm368 56a24 24 0 1 1 0 48 24 24 0 1 1 0-48z\"\/><\/svg><\/a><\/div>';\n\n\n\t\t\t\t\t\t\t\tvar link_text = $form[0].closest('.block-hubspot-form').querySelector('.known-user-download').innerText;\n\t\t\t\t\t\t\t\tvar destination_url = $form[0].closest('.block-hubspot-form').querySelector('.known-user-download').href;\n\t\t\t\t\t\t\t\tvar link_class = $form[0].closest('.block-hubspot-form').querySelector('.known-user-download').classList.toString();\n\n\t\t\t\t\t\t\t\tvar knownUserDownloadClick = {\n\t\t\t\t\t\t\t\t\t'event': 'known_user_download',\n\t\t\t\t\t\t\t\t\t'link_text': link_text,\n\t\t\t\t\t\t\t\t\t'source_page': window.location.href,\n\t\t\t\t\t\t\t\t\t'Referrer': document.referrer,\n\t\t\t\t\t\t\t\t\t'destination_url': destination_url,\n\t\t\t\t\t\t\t\t\t'link_class': link_class,\n\t\t\t\t\t\t\t\t\t'lastAsset': '2025 Contact Centre Trends in APAC (Report)',\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\thsLinkClickTracking();\n\t\t\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.known-user-download').addEventListener('click', () => {\n\t\t\t\t\t\t\t\t\tif (window.dataLayer) {\n\t\t\t\t\t\t\t\t\t\twindow.dataLayer.push(knownUserDownloadClick);\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t*\/\n\n\t\t\t\t\t\t\n\n\n\t\t\t\t\t\tif (gatedContentType === 'contentReveal') {\n\t\t\t\t\t\t\tif (localStorage.getItem('hasSubmittedForm') !== 'true') {\n\t\t\t\t\t\t\t\ttimeoutTime = parseInt(timeoutTime * 1000);\n\n\t\t\t\t\t\t\t\t\tsetTimeout(() => {\n\t\t\t\t\t\t\t\t\t\tdocument.body.classList.add('gated-lock-screen');\n\t\t\t\t\t\t\t\t\t\tdocument.documentElement.classList.add('gated-lock-screen');\n\t\t\t\t\t\t\t\t\t}, timeoutTime);\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\/\/ inject custom field values into Hubspot hidden input names\n\t\t\t\t\t\t\tvar formIDLastAssetData = formIDLastAssetData || [];\n\t\t\t\t\t\t\tformIDLastAssetData.push({\n\t\t\t\t\t\t\t\tid: 'hubspot-form-6a57456405f34',\n\t\t\t\t\t\t\t\tlast_asset: '2025 Contact Centre Trends in APAC (Report)'\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\tvar input = $form[0].querySelector('input[name=\"last_asset\"]');\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\/\/lastAssetInputs.forEach(input => {\n\t\t\t\t\t\t\tif(input && input.closest('.block-hubspot-form')) {\n\t\t\t\t\t\t\t\tvar formId = input.closest('.block-hubspot-form').id;\n\t\t\t\t\t\t\t\tvar formData = formIDLastAssetData.find(item => item.id === formId);\n\n\t\t\t\t\t\t\tif (formData) {\n\t\t\t\t\t\t\t\tinput.value = formData.last_asset;\n\t\t\t\t\t\t\t\tinput.dispatchEvent(new Event('input', {\n\t\t\t\t\t\t\t\t\tbubbles: true\n\t\t\t\t\t\t\t\t}));\n\n\t\t\t\t\t\t\t\tconsole.log(formData.last_asset);\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\/\/});\n\t\t\t\t\t\t\/\/ if (document.querySelector('input[name=\"last_asset\"]')) {\n\t\t\t\t\t\t\/\/ \tdocument.querySelector('input[name=\"last_asset\"]').value = '<\/\/?php echo $last_asset; ?>';\n\t\t\t\t\t\t\/\/ \tdocument.querySelector('input[name=\"last_asset\"]').dispatchEvent(new Event('input', {\n\t\t\t\t\t\t\/\/ \t\tbubbles: true\n\t\t\t\t\t\t\/\/ \t}));\n\n\t\t\t\t\t\t\t\/\/ }\n\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\/\/ After button clicked, but before data is sent\n\t\t\t\t\tfunction onBeforeFormSubmitFunction($form) {\n\t\t\t\t\t\tconst submitButton = $form.find('input[type=\"submit\"]').get(0);\n\n\t\t\t\t\t\t\tif (submitButton) {\n\t\t\t\t\t\t\t\tsubmitButton.classList.add('submit-loading');\n\t\t\t\t\t\t\t\tsubmitButton.value = \"Loading...\";\n\t\t\t\t\t\t\t\tsubmitButton.disabled = true;\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\/\/ Next few functions fire only if ZI enabled\n\t\t\t\t\t\tfunction onEmailChange($form) {\n\t\t\t\t\t\t\tlet emailInput = document.querySelector('input[name=\"email\"]');\n\t\t\t\t\t\t\tif(document.querySelector('input[name=\"Email\"]'))\n\t\t\t\t\t\t\t\temailInput = document.querySelector('input[name=\"Email\"]');\n\n\t\t\t\t\t\tif (emailInput && !emailInput.hasListenersAttached) {\n\t\t\t\t\t\t\t['input', 'change'].forEach(eventType => {\n\t\t\t\t\t\t\t\temailInput.addEventListener(eventType, handleInputChange.bind(null, $form, emailInput));\n\t\t\t\t\t\t\t});\n\n\t\t\t\t\t\t\temailInput.hasListenersAttached = true;\n\t\t\t\t\t\t}\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction handleInputChange($form, emailInput) {\n\t\t\t\t\t\t\/\/console.log('Email input event triggered:', emailInput.value);\n\n\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\tfunction handleZoomInfoMatch($form, emailInput) {\n\t\t\t\t\t\tvalidateEmailWithDelay(emailInput);\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction validateEmailWithDelay(emailInput) {\n\t\t\t\t\t\tvar form = emailInput.closest('form');\n\t\t\t\t\t\tvar submitButton = form.querySelector('[type=\"submit\"]');\n\t\t\t\t\t\t\n\t\t\t\t\t\tfunction disableSubmit() {\n\t\t\t\t\t\t\t\/\/console.log('Disable Submit');\n\t\t\t\t\t\t\tsubmitButton.classList.add('disabled');\n\t\t\t\t\t\t\tsubmitButton.disabled = true;\n\t\t\t\t\t\t}\n\n\t\t\t\t\t\tfunction enableSubmit() {\n\t\t\t\t\t\t\t\/\/console.log('Enable Submit');\n\t\t\t\t\t\t\tsubmitButton.classList.remove('disabled');\n\t\t\t\t\t\t\tsubmitButton.disabled = false;\n\t\t\t\t\t\t}\n\n\t\t\t\t\t\tsetTimeout(() => {\n\t\t\t\t\t\t\tconst neverBounceStatus = emailInput.getAttribute('data-zi-neverbounce-status');\n\t\t\t\t\t\t\t\/\/console.log(neverBounceStatus);\n\n\n\t\t\t\t\t\t\tfetch(inmomentlocalizedata.theme_path + '\/template-parts\/content-blocks\/blocked-domains.json')\n\t\t\t\t\t\t\t.then(response => response.json())\n\t\t\t\t\t\t\t.then(list => {\n\n\t\t\t\t\t\t\t\tvar emailErrorHtml = document.createElement('div');\n\t\t\t\t\t\t\t\temailErrorHtml.setAttribute('class', 'mktoError mktoErrorCustom');\n\t\t\t\t\t\t\t\temailErrorHtml.innerHTML = 'This email is not allowed.';\n\n\n\t\t\t\t\t\t\t\tfunction isDomainFound(email) {\n\t\t\t\t\t\t\t\t\tconst domain = email.split('@')[1];\n\t\t\t\t\t\t\t\t\treturn list.includes(domain);\n\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\tif (isDomainFound(emailInput.value) || neverBounceStatus === 'invalid' || neverBounceStatus === 'disposable') {\n\t\t\t\t\t\t\t\t\tif(!form.querySelector('.mktoErrorCustom'))\n\t\t\t\t\t\t\t\t\t\temailInput.after(emailErrorHtml);\n\t\t\t\t\t\t\t\t\tdisableSubmit();\n\t\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\t\tif(form.querySelector('.mktoErrorCustom'))\n\t\t\t\t\t\t\t\t\t\tform.querySelector('.mktoErrorCustom').remove();\n\t\t\t\t\t\t\t\t\tenableSubmit();\n\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\t})\n\t\t\t\t\t\t\t.catch(error => console.error('Error loading list:', error));\n\n\t\t\t\t\t\t}, 500);\n\t\t\t\t\t}\n\t\t\t\t\t\n\n\t\t\t\t\tfunction onFormSubmitFunction($form) {\n\t\t\t\t\t\t\/\/console.log('onFormSubmit function');\n\t\t\t\t\t\t\/\/ if ($form.attr('id') === 'hsForm_32e872b5-396b-4da6-905d-57c7e16b5b15') {\n\t\t\t\t\t\t\/\/ \t\/\/console.log(\"32e872b5-396b-4da6-905d-57c7e16b5b15 form submit function\");\n\t\t\t\t\t\t\/\/ }\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction onFormSuccessFunction($form, data) {\n\t\t\t\t\t\tif (gatedContentType === 'contentReveal') {\n\t\t\t\t\t\t\tif (localStorage.getItem('hasSubmittedForm') !== 'true') {\n\t\t\t\t\t\t\t\trevealGatedContent();\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t} else if (gatedContentType === 'popupVideo' || gatedContentType === 'heroCTAPopupVideo') {\n\t\t\t\t\t\t\trevealPopupVideo($form);\n\t\t\t\t\t\t} else if (gatedContentType === 'popupPdf') {\n\t\t\t\t\t\t\trevealPopupPdf($form);\n\t\t\t\t\t\t} else if (gatedContentType === 'footerCTAPopupVideo') {\n\t\t\t\t\t\t\trevealFooterPopupVideo()\n\t\t\t\t\t\t} else if (gatedContentType === 'innerGate') {\n\t\t\t\t\t\t\trevealInnerGate($form);\n\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\/\/ GTM add event trigger here\n\t\t\t\t\t\twindow.dataLayer = window.dataLayer || []\n\t\t\t\t\t\twindow.dataLayer.push({\n\t\t\t\t\t\t\t'event': 'form_submit',\n\t\t\t\t\t\t\t'lastAsset': '2025 Contact Centre Trends in APAC (Report)',\n\t\t\t\t\t\t\t'formSubmittedPage': window.location.href,\n\t\t\t\t\t\t\t'salesforceCampaignID': 'Conversational Intelligence Trends Report',\n\t\t\t\t\t\t\t'formType': 'gated',\n\t\t\t\t\t\t\t'gatedContentType': gatedContentType\n\t\t\t\t\t\t});\n\n\t\t\t\t\t\tlocalStorage.setItem('hasSubmittedForm', 'true');\n\n\t\t\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\tfunction revealInnerGate($form) {\n\t\t\t\t\t\tif ($form[0].closest('.block-im-quiz')) {\n\t\t\t\t\t\t\t$form[0].closest('.hs-form-sticky-wrap').classList.add('hidden');\n\t\t\t\t\t\t\t$form[0].closest('.block-im-quiz').querySelector('.im-quiz-finish-screen').classList.remove('hidden');\n\t\t\t\t\t\t\t$form[0].closest('.block-im-quiz').querySelector('.quiz-inner').classList.remove('hidden');\n\t\t\t\t\t\t\t$form[0].closest('.block-im-quiz').querySelector('.restart').style.display = 'inline-block';\n\t\t\t\t\t\t}\n\n\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction revealGatedContent() {\n\t\t\t\t\t\t\/\/console.log('content has been revealed');\n\t\t\t\t\t\tdocument.body.classList.remove('gated-lock-screen');\n\t\t\t\t\t\tdocument.documentElement.classList.remove('gated-lock-screen');\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction revealPopupPdf($form) {\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.submitted-message-custom').classList.remove('hidden');\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.submitted-message').classList.add('hidden');\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.hs-form-title').classList.add('hidden');\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.more-content').classList.add('hidden');\n\t\t\t\t\t\tsetTimeout(() => {\n\t\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.submitted-message-custom .header-cta-button').click();\n\t\t\t\t\t\t}, 3000);\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction revealPopupVideo($form) {\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.play-btn.modal-trigger.form-to-video').click();\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.form-to-video-wrapper').classList.remove('hidden');\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.submitted-message').classList.add('hidden');\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').querySelector('.hs-form-title').classList.add('hidden');\n\t\t\t\t\t\t$form[0].closest('.block-hubspot-form').classList.add('to-video');\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction revealFooterPopupVideo() {\n\t\t\t\t\t\tdocument.querySelector('.play-btn.modal-trigger.form-to-video.footer-cta').click();\n\t\t\t\t\t\tdocument.querySelector('.form-to-video-wrapper.footer-cta').classList.remove('hidden');\n\t\t\t\t\t\tdocument.querySelector('.hs-form-title.footer-cta').classList.add('hidden');\n\t\t\t\t\t\tdocument.querySelector('.hs-form-sticky-wrap.footer-cta-popup-video .block-hubspot-form').classList.add('to-video');\n\t\t\t\t\t\tvar submittedMessages = document.querySelectorAll('.submitted-message');\n\t\t\t\t\t\tsubmittedMessages.forEach(function(submittedMessage) {\n\t\t\t\t\t\t\tsubmittedMessage.classList.add('hidden');\n\t\t\t\t\t\t});\n\t\t\t\t\t}\n\n\t\t\t\t\tfunction gotoScorecard(data) {\n\n\t\t\t\t\t\tvar baseURL = '';\n\t\t\t\t\t\tvar thankYouURLParams = [];\n\t\t\t\t\t\tthankYouURLParams['first_name'] = data.submissionValues.firstname ? data.submissionValues.firstname : '';\n\t\t\t\t\t\tthankYouURLParams['last_name'] = data.submissionValues.lastname ? data.submissionValues.lastname : '';\n\t\t\t\t\t\tthankYouURLParams['email'] = data.submissionValues.email ? data.submissionValues.email : '';\n\t\t\t\t\t\tthankYouURLParams['phone_number'] = data.submissionValues.phone ? data.submissionValues.phone : '5555555555';\n\n\t\t\t\t\t\tthankYouURLParams = Object.entries(thankYouURLParams);\n\t\t\t\t\t\tvar queryString = thankYouURLParams.map(([key, value]) =>\n\t\t\t\t\t\t\t`${encodeURIComponent(key)}=${encodeURIComponent(value)}`).join('&');\n\n\n\t\t\t\t\t\tvar finalThankyouURL = `${baseURL}?${queryString}&suppress_fields`;\n\n\t\t\t\t\t\twindow.open(finalThankyouURL, '_blank');\n\n\t\t\t\t\t}\n\t\t\t\t\t\/\/ Returns the redirect URL needed for the Hubspot form\n\t\t\t\t\tfunction generateThankYouURL(customURL, formType, gatedContentType, gatedAsset, $form) {\n\t\t\t\t\t\t\/\/ Check if custom Thank You URL is needed\n\t\t\t\t\t\tif (!customURL) {\n\t\t\t\t\t\t\tvar baseURL =\n\t\t\t\t\t\t\t\t'https:\/\/inmoment.com\/en-au\/thank-you\/?';\n\t\t\t\t\t\t\tvar thankYouURLParams = [];\n\n\t\t\t\t\t\t\tif (formType === 'gated') {\n\t\t\t\t\t\t\t\tif (gatedContentType === 'pdf') {\n\t\t\t\t\t\t\t\t\tthankYouURLParams['type'] = 'asset';\n\t\t\t\t\t\t\t\t\t\/\/ Gated content needs to be attachment URL\n\t\t\t\t\t\t\t\t\tthankYouURLParams['asset'] = gatedAsset;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'video') {\n\t\t\t\t\t\t\t\t\tthankYouURLParams['type'] = 'video';\n\t\t\t\t\t\t\t\t\t\/\/ Gated content needs to be attachment URL\n\t\t\t\t\t\t\t\t\tthankYouURLParams['asset'] = gatedAsset;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'popupVideo') {\n\t\t\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'contentReveal') {\n\t\t\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'heroCTAPopupVideo') {\n\t\t\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'footerCTAPopupVideo') {\n\t\t\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'popupPdf') {\n\t\t\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t\t\t} else if (gatedContentType === 'innerGate') {\n\t\t\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\/\/console.log('gatedAsset -> ', gatedAsset);\n\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\tif (formType === 'demo') {\n\t\t\t\t\t\t\t\tthankYouURLParams['type'] = 'contact';\n\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\tif (formType === 'contact') {\n\t\t\t\t\t\t\t\tthankYouURLParams['type'] = 'contact';\n\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\tif (formType === 'event') {\n\t\t\t\t\t\t\t\tthankYouURLParams['type'] = 'event';\n\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\/\/console.log('thankYouURLParams -> ', thankYouURLParams);\n\t\t\t\t\t\t\t\/\/ Construct the query string by joining the key-value pairs\n\t\t\t\t\t\t\tthankYouURLParams = Object.entries(thankYouURLParams);\n\n\t\t\t\t\t\t\tvar queryString = thankYouURLParams.map(([key, value]) =>\n\t\t\t\t\t\t\t\t`${encodeURIComponent(key)}=${encodeURIComponent(value)}`).join('&');\n\n\t\t\t\t\t\t\t\/\/console.log('queryString -> ', queryString);\n\t\t\t\t\t\t\t\/\/ Combine the base URL with the query string\n\t\t\t\t\t\t\tvar finalThankyouURL = `${baseURL}${queryString}`;\n\n\t\t\t\t\t\t\t\/\/console.log('finalThankyouURL -> ', finalThankyouURL);\n\t\t\t\t\t\t\treturn finalThankyouURL;\n\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\/\/console.log('customURL -> ', customURL);\n\t\t\t\t\t\t\treturn customURL;\n\t\t\t\t\t\t}\n\t\t\t\t\t}\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\tif (document.querySelector('#hubspot-form-6a57456405f34')) {\n\t\t\t\t\t\t\t\t\tvar observer = new IntersectionObserver(function(el) {\n\t\t\t\t\t\t\t\t\t\t\tel = el[0] ? el[0] : el;\n\t\t\t\t\t\t\t\t\t\t\tif (el.isIntersecting) {\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\t\t\t\t\t\tfunction mktoFormLoaded(form) {\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tvar formEl = form.getFormElem();\n\t\t\t\t\t\t\tconsole.log('mktoform', form, formEl[0].querySelector(\"style\"))\n\t\t\t\t\t\t\t\/\/MktoForms2.whenReady(function() {onFormReadyFunction(formEl)});\n\t\t\t\t\t\t\tdocument.getElementById('mktoForms2BaseStyle').remove();\n\t\t\t\t\t\t\tdocument.getElementById('mktoForms2ThemeStyle').remove();\n\t\t\t\t\t\t\tformEl[0].querySelector(\"style\").remove();\n\t\t\t\t\t\t\tconsole.log(formEl[0].querySelector(\"style\"))\n\n\t\t\t\t\t\t\tonFormReadyFunction(formEl);\n\n\t\t\t\t\t\t\tformEl[0].querySelector('[type=\"submit\"]').innerText = 'Submit';\n\n\n\t\t\t\t\t\t\tif(formEl[0].closest('.block-hubspot-form').querySelector('.skeleton-loader'))\n\t\t\t\t\t\t\t\tformEl[0].closest('.block-hubspot-form').querySelector('.skeleton-loader').style.display = 'none';\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\tform.onSubmit(function() {onFormSubmitFunction(formEl)});\n\t\t\t\t\t\t\tform.onSuccess(function() {\n\t\t\t\t\t\t\t\tonFormSuccessFunction(formEl);\n\t\t\t\t\t\t\t\twindow.location.assign(generateThankYouURL('',\n\t\t\t\t\t\t\t\t\t'gated', 'pdf',\n\t\t\t\t\t\t\t\t\t'90305'));\n\n\t\t\t\t\t\t\t\treturn false;\n\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\/\/onFormSubmitFunction($form);\n\t\t\t\t\t\t\t\/\/onFormSuccessFunction($form, data);\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t}\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tif(document.getElementById('mktoForm_2179') && !document.getElementById('mktoForm_2179' ).innerHTML.trim())\n\t\t\t\t\t\t\t\tMktoForms2.loadForm(\"\/\/go.forsta.com\", \"972-OEC-621\", 2179, mktoFormLoaded);\n\n\t\t\t\t\t\treturn;\n\t\t\t\t\t\t\n\t\t\t\t\t\t\/\/ Main hubspot code\n\t\t\t\t\t\thbspt.forms.create({\n\t\t\t\t\t\t\tregion: \"na1\",\n\t\t\t\t\t\t\tportalId: \"1787915\",\n\t\t\t\t\t\t\tlocale: \"en\",\n\t\t\t\t\t\t\ttarget: \"#hubspot-form-6a57456405f34 .form_target\",\n\t\t\t\t\t\t\tcss: '',\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tredirectUrl: generateThankYouURL('',\n\t\t\t\t\t\t\t\t\t'gated', 'pdf',\n\t\t\t\t\t\t\t\t\t'90305'),\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tformId: \"32e872b5-396b-4da6-905d-57c7e16b5b15\",\n\t\t\t\t\t\t\tmanuallyBlockedEmailDomain: [\"mailinator.com\",\"mailor.com\",\"yahoi.co.uk\",\"art.suez.edu.eg\",\"eol.com\",\"info.com\",\"weizixu.com\",\"naymedia.com\",\"compny.com\",\"linator.com\",\"edu.com\",\"mailinaor.com\",\"sportrid.comm\",\"tufufacenurimyv.com\",\"eeeqwe2.com\",\"armyspy.com\",\"info.net\",\"hinoon.com\",\"ainator.com\",\"busniess.com\",\"GMAIL1.com\",\"alright.com\",\"example.com\",\"poverts.com\",\"mailt.com\",\"apxby.com\",\"gmail.com\",\"yahoo.com\",\"hotmail.com\",\"live.com\",\"aol.com\",\"outlook.com\",\"qq.com\",\"comcast.com\",\"icloud.com\",\"ctpagent.com\",\"wesolvecx.com\",\"getthematic.com\",\"merkle.com\",\"getlocalmeasure.com\",\"localmeasure.com\",\"asknicely.com\",\"nielseniq.com\",\"momentive.com\",\"reputation.com\",\"zenloop.com\",\"eloquant.com\",\"hellocustomer.com\",\"skeepers.io\",\"yabble.com\",\"resonate.com.au\",\"smg.com\",\"altointelligence.co.uk\",\"altointelligence.com\",\"auracorp.com\",\"bareinternational.com\",\"bestmark.com\",\"blauw.com\",\"clarabridge.com\",\"concentrix.com\",\"concur.com\",\"confirmit.com\",\"copytimize.com\",\"critizr.com\",\"crowdicity.com\",\"customerradar.com\",\"customersat.com\",\"gallup.com\",\"getfeedback.com\",\"gfk.com\",\"globis-consulting.de\",\"glowfeed.com\",\"insync.com.au\",\"intervista.ch\",\"iperceptions.com\",\"jacada.com\",\"ka-brandresearch.com\",\"kantar.com\",\"kantartns.com\",\"kunden-insights.de\",\"link.ch\",\"livinglens.tv\",\"Loyalty360.org\",\"management-consult.de\",\"medallia.com\",\"morpace.com\",\"nice.com\",\"niceincontact.com\",\"op2ma.com.au\",\"opinionlab.com\",\"oracle.com\",\"pangealabs.com\",\"pidas.com\",\"potentiate.com\",\"quadient.com\",\"qualtrics.com\",\"questback.com\",\"rateitapp.com\",\"rateitapp.com.au\",\"responsetek.com\",\"rightnow.com\",\"salesforce.com\",\"sap.com\",\"satmetrix.com\",\"slmedien.de\",\"smg.com\",\"sphanalytics.com\",\"stellarbpo.com\",\"stellarxm.com\",\"strikedeck.com\",\"surveygizmo.com\",\"surveymonkey.com\",\"tele-research.de\",\"themsrgroup.com\",\"tns-global.com\",\"tns-infratest.com\",\"tnsglobal.com\",\"touchpointgroup.com\",\"ttr-group.de\",\"united-research.com\",\"usabilla.com\",\"verint.com\",\"vovici.com\",\"walkerinfo.com\",\"zendesk.com\",\"zingle.com\"],\n\n\t\t\t\t\t\t\t\t\t\t\t\t\/\/ Arbitrary in case there are two of same form on page\n\t\t\t\t\t\t\t\t\t\t\t\tformInstanceId: \"hubspot-form-6a57456405f34\",\n\n\n\n\t\t\t\t\t\t\t\t\t\t\t\tonFormReady: function($form) {\n\t\t\t\t\t\t\t\t\t\t\t\t\tonFormReadyFunction($form);\n\t\t\t\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\tonBeforeFormSubmit: function($form) {\n\t\t\t\t\t\t\t\t\t\t\t\t\tonBeforeFormSubmitFunction($form);\n\t\t\t\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\tonFormSubmit: function($form) {\n\t\t\t\t\t\t\t\t\t\t\t\t\tonFormSubmitFunction($form);\n\t\t\t\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\tonFormSubmitted: function($form, data) {\n\t\t\t\t\t\t\t\t\t\t\t\t\tonFormSuccessFunction($form, data);\n\n\t\t\t\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\tsubmitText: \"Submit\",\n\t\t\t\t\t\t\t\t\t\t\t});\n\n\t\t\t\t\t\t\t\t\t\t\t observer.unobserve(el.target);\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t}, {\n\t\t\t\t\t\t\t\t\troot: null,\n\t\t\t\t\t\t\t\t\trootMargin: '0px 0px 50% 0px',\n\t\t\t\t\t\t\t\t\tthreshold: 0.1\n\t\t\t\t\t\t\t\t});\n\n\t\t\t\t\t\t\tvar targetElement = document.querySelector('#hubspot-form-6a57456405f34'); observer.observe(targetElement.parentElement);\n\t\t\t\t\t\t}\n\n\n\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t}) \/\/ on hs script loaded\n\t\t\t<\/script>\n\n\n\t\t\t\n\n\t\t\t\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t<form id=\"mktoForm_2179\" ><\/form>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t<\/div>\n\n\n\t\t\t\t\t\t\n\t\t\t<div class=\"gated-featured-asset-block-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"gated-featured-asset-block-heading color-orca\">The Call That Should Have Never Happened<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gated-featured-asset-block-text-content color-orca\">\n\t\t\t\t\t\t<ul>\n<li>Still flooded with preventable calls?<\/li>\n<li>Still investing in AI tools that don\u2019t change outcomes?<\/li>\n<li>Still training agents to fix problems they didn\u2019t create?<\/li>\n<\/ul>\n<p>This report is for you.<\/p>\n<p>InMoment surveyed<strong> over 1,200 consumers across Asia-Pacific<\/strong> to uncover what\u2019s really driving customer contact \u2014 and what leading brands are doing differently to reduce costs, improve agent performance, and deliver better customer outcomes.<\/p>\n<p><strong>What you\u2019ll learn:<\/strong><\/p>\n<ul>\n<li>The real source of inbound volume (and how to stop it at the source)<\/li>\n<li>What consumers want from digital support, and why current AI tools aren\u2019t delivering<\/li>\n<li>How contact centres can move from reactive firefighting to strategic growth<\/li>\n<\/ul>\n<p>Consumer expectations have shifted. Your strategy should too.<\/p>\n<p>Download the full report to find out how to transform your contact centre into a smarter, more efficient engine for customer experience.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/section>\n\n\n\n<section id=\"block-5e2654d325b10d55a31fdfaaf6d87d78\" class=\"content-block client-logo-bar-block default alignfull no-background\" style=\"\">\n\t<div class=\"logo-bar-wrapper\">\n\n\t\t<div class=\"default-bar bar-grid grid grid-nogutter background-great-white\">\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-298710749\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/02\/specsavers-logo-300x115.png\" alt=\"Specsavers logo\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Visionary CX: Specsavers\u2019 Journey From Traditional to Transformational CX<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-2701142972\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/Medibank_logo-137.svg\" alt=\"\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Medibank<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-3927426843\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/suncorp-logo-300x98.png\" alt=\"Suncorp\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Suncorp<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-2938541327\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-300x103.png\" alt=\"EML\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">EML<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-3889662229\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/rest-logo-300x122.png\" alt=\"\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">REST Super<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-424872535\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2021\/03\/csc-300x105.png\" alt=\"\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Commonwealth Superannuation Corporation (CSC)<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-4243762290\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-300x88.png\" alt=\"Bank of Queensland\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Bank of Queensland<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-1015172770\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-300x48.png\" alt=\"legalsuper\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">legalsuper<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-137016172\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/11\/jax-tyres.png\" alt=\"\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">JAX Tyres &amp; Auto Drives Success with InMoment\u2019s Reputation Management Technology<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-2448255133\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-300x37.png\" alt=\"Honda\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Honda<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-233682570\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-300x106.png\" alt=\"ASICS\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">ASICS<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-1724858756\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/01\/Yo-Chi.png\" alt=\"\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Yo-Chi Increases Location Foot Traffic by 92% in Less Than a Year<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-2268790095\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-300x53.png\" alt=\"Solotel\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Solotel Group Captures a 129% Increase In Online Reviews<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"col col-middle col-align-middle single-logo \">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"image-btn modal-trigger no-hover\" data-toggle=\"modal\" data-target=\".client-content-4156073999\" style=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"object-contain absolute top-0 left-0 w-full h-full\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-lazy=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/03\/bettys-logo-color-300x148.png\" alt=\"Betty's Burgers\" \/>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">How Betty\u2019s Burgers Transformed Customer Feedback Into Online Reputation Growth<\/span>\n\t\t\t\t\t\t\t<\/a>\n\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- single-logo -->\n\n\t\t\t\t<!-- $client_img -->\n\n\t\t\t<!-- end foreach $clientlogos -->\n\t\t<\/div><!-- .bar grid -->\n\n\t\t\n\t\t<!-- First Modal - Content Modal -->\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-298710749\" id=\"content-modal-298710749\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"383\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/02\/specsavers-logo.png\" class=\"logo-image\" alt=\"Specsavers logo\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/02\/specsavers-logo.png 1000w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/02\/specsavers-logo-300x115.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/02\/specsavers-logo-768x294.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">We completed a comprehensive scan of all the top global providers, and it was very clear that InMoment not only had the best Platform capabilities, but also the best support and guidance to help Specsavers.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-attribution \">Gareth Dixon, Director of Central Operations at Specsavers<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/Specsavers-Case-Study.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"play-btn modal-trigger \" data-toggle=\"modal\" data-target=\".video-content-2463948664\" data-url=\"https:\/\/player.vimeo.com\/video\/1053949737?h=45e7a05981&amp;dnt=1&amp;app_id=122963&amp;autohide=1&amp;controls=1&amp;hd=1&amp;pause=0&amp;videoFoam=true\">Play Video<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-video video-content-2463948664\" id=\"video-modal-2463948664\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" data-target=\".video-content-2463948664\" aria-label=\"Close video\"><\/button>\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\t\t\t\t\t\t\t\t\t\t<iframe loading=\"lazy\" title=\"Specsavers\u2019 Journey From Traditional to Transformational CX (ANZ)\" src=\"https:\/\/player.vimeo.com\/video\/1053949737?h=45e7a05981&amp;dnt=1&amp;app_id=122963&#038;autohide=1&#038;controls=1&#038;hd=1&#038;pause=0&#038;videoFoam=true\" width=\"950\" height=\"534\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #video-modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-2701142972\" id=\"content-modal-2701142972\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/Medibank_logo-137.svg\" class=\"logo-image\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">Medibank was awarded the winner of &quot;Best CX Transformation&quot; after record-breaking service and NPS scores, an increase in market share, and a reduction in overall customer complaints!<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/Medibank-Client-Story-1.pdf\" download><span>Download Now<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-3927426843\" id=\"content-modal-3927426843\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"951\" height=\"310\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/suncorp-logo.png\" class=\"logo-image\" alt=\"Suncorp\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/suncorp-logo.png 951w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/suncorp-logo-300x98.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/suncorp-logo-768x250.png 768w\" sizes=\"auto, (max-width: 951px) 100vw, 951px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">Shortlisted for the 2023 Best CX Transformation at the CX Awards<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-2938541327\" id=\"content-modal-2938541327\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"4465\" height=\"1531\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo.png\" class=\"logo-image\" alt=\"EML\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo.png 4465w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-300x103.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-1024x351.png 1024w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-768x263.png 768w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-1536x527.png 1536w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-2048x702.png 2048w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/eml-logo-1920x658.png 1920w\" sizes=\"auto, (max-width: 4465px) 100vw, 4465px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">Winner of the 2019 Best CX Transformation Award<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-3889662229\" id=\"content-modal-3889662229\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"264\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/rest-logo.png\" class=\"logo-image\" alt=\"\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/rest-logo.png 650w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/rest-logo-300x122.png 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">The surveys so far have given us incredible results and fast tracked the relevant insights that were meaningful for us. At the same time, InMoment has focused on building the right case management program for us and really supported us along the way. And we\u2019re constantly tweaking our program now to ensure we\u2019re recovering customers, engaging people and turning them from a passive into a promoter.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-424872535\" id=\"content-modal-424872535\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2021\/03\/Commonwealth-Superannuation-Corporation-Case-Study.pdf\" download><span>Download Now<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-4243762290\" id=\"content-modal-4243762290\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2512\" height=\"738\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq.png\" class=\"logo-image\" alt=\"Bank of Queensland\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq.png 2512w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-300x88.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-1024x301.png 1024w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-768x226.png 768w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-1536x451.png 1536w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-2048x602.png 2048w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/boq-1920x564.png 1920w\" sizes=\"auto, (max-width: 2512px) 100vw, 2512px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">Shortlisted for the 2023 Best CX Transformation award.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-1015172770\" id=\"content-modal-1015172770\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2200\" height=\"354\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper.png\" class=\"logo-image\" alt=\"legalsuper\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper.png 2200w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-300x48.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-1024x165.png 1024w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-768x124.png 768w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-1536x247.png 1536w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-2048x330.png 2048w, https:\/\/inmoment.com\/wp-content\/uploads\/2020\/09\/legalsuper-1920x309.png 1920w\" sizes=\"auto, (max-width: 2200px) 100vw, 2200px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">When we first selected InMoment, we had a fantastic and smooth experience transitioning from the sales process to our client success team. We were really impressed by the kick-off meeting, the accessibility and the dedication we received from the whole process. We were so impressed, that we are taking that experience and trying to replicate it across our own relationship management at legalsuper!<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-attribution \">legalsuper\u2019s Manager of Insights and Service Design<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/05\/legalsuper-case-study.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-137016172\" id=\"content-modal-137016172\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"221\" height=\"33\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2020\/11\/jax-tyres.png\" class=\"logo-image\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">\u201cInMoment got involved in our business and culture journey, designed an experience improvement plan, and really helped us understand what the franchisees needed to do better with their businesses.&quot;<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-attribution \">Steve Grossreider, CEO of JAX Tyres &amp; Auto<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/01\/jax-reputation-management.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-2448255133\" id=\"content-modal-2448255133\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"315\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo.png\" class=\"logo-image\" alt=\"Honda\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo.png 2560w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-300x37.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-1024x126.png 1024w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-768x95.png 768w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-1536x189.png 1536w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-2048x252.png 2048w, https:\/\/inmoment.com\/wp-content\/uploads\/2024\/03\/honda-logo-1920x236.png 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">Using customer insights, Honda Australia spearheaded a massive change in legacy dealership models, turning toward a brand-new customer-centric method for selling its cars.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2024\/07\/Driving-CX-Forward-with-Honda.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-233682570\" id=\"content-modal-233682570\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"901\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo.png\" class=\"logo-image\" alt=\"ASICS\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo.png 2560w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-300x106.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-1024x360.png 1024w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-768x270.png 768w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-1536x541.png 1536w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-2048x721.png 2048w, https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/asics-logo-1920x676.png 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">In 2020, ASICS turned its focus on customer experience. By 2022, the program had rolled out to 27 countries. ASICS uses its experience program to get quantitative benchmarks for quality store experience, to learn why customers visit the stores, and to find ways to improve the store experience. With direct contact to frontline teams, response volume would see a 40% month on month lift with a corresponding increase of +19% of direct CX sales.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-attribution \">Tabia Chui, Manager, Retail Promotions Department, ASICS<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2023\/10\/Launching-and-Scaling-a-Global-CX-Program.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-2268790095\" id=\"content-modal-2268790095\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2965\" height=\"521\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel.png\" class=\"logo-image\" alt=\"Solotel\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel.png 2965w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-300x53.png 300w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-1024x180.png 1024w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-768x135.png 768w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-1536x270.png 1536w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-2048x360.png 2048w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/solotel-1920x337.png 1920w\" sizes=\"auto, (max-width: 2965px) 100vw, 2965px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">Any customer-facing brand will live and die with reviews. We needed a solution that could help us maintain social proof for our brands\u2014the ones that are brand new, and the ones that have been open and thriving for 25+ years.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-attribution \">Justin Wei, Head of UX &amp; Customer Marketing, Solotel Group<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/02\/Solotel-Case-Study.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t\n\t\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"modal fade modal-client client-content-4156073999\" id=\"content-modal-4156073999\" tabindex=\"-1\" role=\"dialog\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"modal-dialog\" role=\"document\">\n\t\t\t\t\t\t\t<div class=\"modal-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"modal-body\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"embed-responsive embed-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col col-12 testimonial-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"380\" height=\"188\" src=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/03\/bettys-logo-color.png\" class=\"logo-image\" alt=\"Betty&#039;s Burgers\" srcset=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/03\/bettys-logo-color.png 380w, https:\/\/inmoment.com\/wp-content\/uploads\/2025\/03\/bettys-logo-color-300x148.png 300w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-testimonial \">&quot;The only advice I have for other professionals is that I wish we invested in ReviewTrackers sooner!&quot;<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"client-attribution \">Janice Verdan, Marketing, Betty\u2019s Burgers<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .testimonial-content -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-group\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"button download pdf-btn  \" href=\"https:\/\/inmoment.com\/wp-content\/uploads\/2025\/03\/Bettys-Burgers-Case-Study.pdf\" download><span>Download PDF<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .button-group -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- embed-container -->\n\n\t\t\t\t\t\t\t\t<\/div><!-- .modal-body -->\n\n\t\t\t\t\t\t\t<\/div><!--- .modal-content -->\n\t\t\t\t\t\t<\/div><!-- .modal-dialog -->\n\t\t\t\t\t<\/div><!-- #content-modal -->\n\t\t\t\t\n\t\t\t\t<!-- Second Modal: Video Modal -->\n\t\t\t\t<!-- $client_video  -->\n\t\t\t<!-- $client_img -->\n\n\t\t<!-- end modal foreach -->\n\n\t<\/div><!-- .logo-bar-wrapper -->\n\t<!-- $client_logos -->\n<\/section><!-- .client-logo-bar-block -->\n\n\n\n<div style=\"margin-top:-175px;\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":90338,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-90303","lp","type-lp","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/inmoment.com\/en-au\/wp-json\/wp\/v2\/lp\/90303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inmoment.com\/en-au\/wp-json\/wp\/v2\/lp"}],"about":[{"href":"https:\/\/inmoment.com\/en-au\/wp-json\/wp\/v2\/types\/lp"}],"version-history":[{"count":0,"href":"https:\/\/inmoment.com\/en-au\/wp-json\/wp\/v2\/lp\/90303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inmoment.com\/en-au\/wp-json\/wp\/v2\/media\/90338"}],"wp:attachment":[{"href":"https:\/\/inmoment.com\/en-au\/wp-json\/wp\/v2\/media?parent=90303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}